{"id":1523,"date":"2026-05-05T22:53:12","date_gmt":"2026-05-06T01:53:12","guid":{"rendered":"https:\/\/semanariolaprensa.com\/avantpremiere\/?p=1523"},"modified":"2026-05-05T23:14:07","modified_gmt":"2026-05-06T02:14:07","slug":"se-registra-gran-adhesion-de-publico-a-las-seis-funciones-del-festival-todos-a-maldonado-nuevo-2026","status":"publish","type":"post","link":"https:\/\/semanariolaprensa.com\/avantpremiere\/se-registra-gran-adhesion-de-publico-a-las-seis-funciones-del-festival-todos-a-maldonado-nuevo-2026\/","title":{"rendered":"Se registra gran adhesi\u00f3n de p\u00fablico a las seis funciones del Festival \u201cTodos a Maldonado Nuevo\u201d 2026"},"content":{"rendered":"\n<p>Del 15 de mayo al 10 de junio se desarrollar\u00e1n las propuestas de teatro local enmarcadas en la quinta edici\u00f3n del mencionado Festival que tendr\u00e1 al Centro Cultural Maldonado Nuevo como escenario de lujo. Ser\u00e1n funciones gratuitas y se invita a las instituciones educativas y sociales, as\u00ed como al p\u00fablico en general, a disfrutar de las obras. La capacidad de la Sala es limitada, por lo que es necesario reservar previamente comunic\u00e1ndose al tel\u00e9fono del Centro Cultural -4226 8635- entre las 8 y las 22 horas.<\/p>\n\n\n\n<p>En la actividad de lanzamiento del Festival, llevada a cabo este martes 5, se dieron a conocer todos los detalles de la nueva edici\u00f3n. En tal sentido, se inform\u00f3 que la programaci\u00f3n se conformar\u00e1 de la siguiente manera:<\/p>\n\n\n\n<p><strong>Mayo<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Viernes&nbsp;15, a las 14 horas:&nbsp;<\/strong><em>De familia bien<\/em>,&nbsp;direcci\u00f3n de Emiliana Silva.<\/li>\n\n\n\n<li><strong>Viernes<\/strong>&nbsp;<strong>22, a partir de las 10 horas:<\/strong>&nbsp;<em>Ecococo<\/em>,&nbsp;direcci\u00f3n deSandra Baylac.<\/li>\n\n\n\n<li><strong>Jueves&nbsp;28, comenzando a la hora 10:<\/strong>&nbsp;<em>El rojo orgulloso<\/em>,&nbsp;de Mario Erramuspe<\/li>\n\n\n\n<li><strong>S\u00e1bado 30, desde las 20 horas:<\/strong>&nbsp;<em>Excluidos<\/em>, direcci\u00f3n deEmiliana Silva.<\/li>\n<\/ul>\n\n\n\n<p><strong>Junio<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mi\u00e9rcoles 3, a partir de las 14 horas:&nbsp;<\/strong><em>Suculentas<\/em>,&nbsp;de Circo Ra\u00edz.<\/li>\n\n\n\n<li><strong>Mi\u00e9rcoles<\/strong>&nbsp;<strong>10, desde la hora 10:&nbsp;<\/strong><em>Que todo el mundo lo sepa<\/em>, direcci\u00f3n de Sebasti\u00e1n Barrios.<\/li>\n<\/ul>\n\n\n\n<p><em><strong>Todos a Maldonado Nuevo<\/strong><\/em><\/p>\n\n\n\n<p>Durante el lanzamiento el director general del Departamento de Cultura de la IDM, Andr\u00e9s Rapetti, expres\u00f3 que una de las primeras tareas que le pidi\u00f3 a Sebasti\u00e1n Barrios, \u201cquien es un poco el gestor cultural y motor de este Ciclo\u201d fue la producci\u00f3n de contenidos al momento de integrarse al equipo de este Centro Cultural que es liderado por su coordinadora, Mariana Mastr\u00e1ngelo.<\/p>\n\n\n\n<p>El jerarca record\u00f3 que desde el principio se dedicaron a \u201cla generaci\u00f3n de un p\u00fablico compuesto por gente del barrio pero tambi\u00e9n de otros lugares para que se familiarizara con este Centro Cultural y generara un v\u00ednculo con la poblaci\u00f3n local\u201d. Asimismo, sostuvo que este Festival \u201ctiene el condimento de que est\u00e1 orientado a elencos, a compa\u00f1\u00edas teatrales locales que consiste en una oportunidad para los artistas locales\u201d.&nbsp;<br>A lo largo de los \u00faltimos cinco a\u00f1os este Centro Cultural se fue convirtiendo en un espacio vivo, habitado y apropiado por su comunidad. Gran parte de la programaci\u00f3n nace de ah\u00ed, de los procesos que crecieron dentro del propio centro: los talleres, la formaci\u00f3n, los grupos que se consolidaron en el tiempo.<\/p>\n\n\n\n<p>En la quinta edici\u00f3n del festival&nbsp;<em>Todos a Maldonado Nuevo<\/em>, el espect\u00e1culo encargado de la apertura ser\u00e1&nbsp;<em>De familia bien<\/em>: una creaci\u00f3n del Taller de Teatro de Adultos del Centro Cultural Maldonado Nuevo.<\/p>\n\n\n\n<p>En el transcurso de los meses de mayo y junio tambi\u00e9n formar\u00e1n parte de la propuesta compa\u00f1\u00edas que han apoyado este proceso desde adentro, y se complementa con creaciones dirigidas a las infancias donde el juego, el teatro y el circo se vuelven herramientas para pensar el mundo desde edades tempranas. Por otra parte, las escuelas, los liceos y las organizaciones sociales le dan sentido a la propuesta gracias a su participaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>El Centro Cultural Maldonado Nuevo est\u00e1 ubicado en calles Agapito Parabera y Miguel Tari, y se reitera que todas las funciones se concretar\u00e1n con entrada gratuita y mediante previa reserva al tel\u00e9fono&nbsp;<strong>4226 8635.<\/strong>&nbsp;<\/p>\n\n\n\n<p><strong>Se puede ampliar la informaci\u00f3n sobre la programaci\u00f3n en el archivo adjunto.<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/maldonado.gub.uy\/sites\/default\/files\/2026-05\/TEATRO%20LOCAL%20todos%20a%20maldonado%20nuevo_0.pdf\"><\/a><\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\" style=\"--aspect-ratio:calc(1024 \/ 683)\"><div class=\"wp-block-jetpack-slideshow_container swiper\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1532\" data-id=\"1532\" data-aspect-ratio=\"1024 \/ 683\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo4.jpeg?resize=1024%2C683&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo4.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo4.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo4.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo4.jpeg?resize=750%2C500&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo4.jpeg?resize=1140%2C760&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo4.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"656\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1533\" data-id=\"1533\" data-aspect-ratio=\"1024 \/ 656\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo1.jpeg?resize=1024%2C656&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo1.jpeg?resize=1024%2C656&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo1.jpeg?resize=300%2C192&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo1.jpeg?resize=768%2C492&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo1.jpeg?resize=750%2C481&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo1.jpeg?resize=1140%2C731&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo1.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1534\" data-id=\"1534\" data-aspect-ratio=\"1024 \/ 683\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo9.jpeg?resize=1024%2C683&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo9.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo9.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo9.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo9.jpeg?resize=750%2C500&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo9.jpeg?resize=1140%2C760&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo9.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1530\" data-id=\"1530\" data-aspect-ratio=\"1024 \/ 683\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo3.jpeg?resize=1024%2C683&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo3.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo3.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo3.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo3.jpeg?resize=750%2C500&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo3.jpeg?resize=1140%2C760&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo3.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1531\" data-id=\"1531\" data-aspect-ratio=\"1024 \/ 683\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo5.jpeg?resize=1024%2C683&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo5.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo5.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo5.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo5.jpeg?resize=750%2C500&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo5.jpeg?resize=1140%2C760&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo5.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1528\" data-id=\"1528\" data-aspect-ratio=\"1024 \/ 683\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo8.jpeg?resize=1024%2C683&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo8.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo8.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo8.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo8.jpeg?resize=750%2C500&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo8.jpeg?resize=1140%2C760&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo8.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1529\" data-id=\"1529\" data-aspect-ratio=\"1024 \/ 683\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo10.jpeg?resize=1024%2C683&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo10.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo10.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo10.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo10.jpeg?resize=750%2C500&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo10.jpeg?resize=1140%2C760&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo10.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1524\" data-id=\"1524\" data-aspect-ratio=\"1024 \/ 683\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo11.jpeg?resize=1024%2C683&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo11.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo11.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo11.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo11.jpeg?resize=750%2C500&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo11.jpeg?resize=1140%2C760&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo11.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1525\" data-id=\"1525\" data-aspect-ratio=\"1024 \/ 683\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo2.jpeg?resize=1024%2C683&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo2.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo2.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo2.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo2.jpeg?resize=750%2C500&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo2.jpeg?resize=1140%2C760&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo2.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1526\" data-id=\"1526\" data-aspect-ratio=\"1024 \/ 683\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo6.jpeg?resize=1024%2C683&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo6.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo6.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo6.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo6.jpeg?resize=750%2C500&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo6.jpeg?resize=1140%2C760&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo6.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-1527\" data-id=\"1527\" data-aspect-ratio=\"1024 \/ 683\" src=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo7.jpeg?resize=1024%2C683&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo7.jpeg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo7.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo7.jpeg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo7.jpeg?resize=750%2C500&amp;ssl=1 750w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo7.jpeg?resize=1140%2C760&amp;ssl=1 1140w, https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo7.jpeg?w=1200&amp;ssl=1 1200w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/TEATRO-LOCAL-todos-a-maldonado-nuevo_0.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de TEATRO LOCAL todos a maldonado nuevo_0.\"><\/object><a id=\"wp-block-file--media-69ba28a0-2470-4ecb-b47f-879717cc3b5a\" href=\"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/TEATRO-LOCAL-todos-a-maldonado-nuevo_0.pdf\">TEATRO LOCAL todos a maldonado nuevo_0<\/a><a href=\"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/TEATRO-LOCAL-todos-a-maldonado-nuevo_0.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-69ba28a0-2470-4ecb-b47f-879717cc3b5a\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Del 15 de mayo al 10 de junio se desarrollar\u00e1n las propuestas de teatro local enmarcadas en la quinta edici\u00f3n del mencionado Festival que tendr\u00e1 al Centro Cultural Maldonado Nuevo como escenario de lujo. Ser\u00e1n funciones gratuitas y se invita a las instituciones educativas y sociales, as\u00ed como al p\u00fablico en general, a disfrutar de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_override_bookmark_settings":[],"jnews_social_meta":[],"jnews_review":[],"enable_review":"","type":"","name":"","summary":"","brand":"","sku":"","good":[],"bad":[],"score_override":"","override_value":"","rating":[],"price":[],"jnews_override_counter":[],"footnotes":""},"categories":[96,415,416],"tags":[],"class_list":["post-1523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cartelera","category-cultura","category-locales"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/semanariolaprensa.com\/avantpremiere\/wp-content\/uploads\/2026\/05\/cultura-maldonado-nuevo8.jpeg?fit=1200%2C800&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/posts\/1523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/comments?post=1523"}],"version-history":[{"count":2,"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/posts\/1523\/revisions"}],"predecessor-version":[{"id":1538,"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/posts\/1523\/revisions\/1538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/media\/1528"}],"wp:attachment":[{"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/media?parent=1523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/categories?post=1523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semanariolaprensa.com\/avantpremiere\/wp-json\/wp\/v2\/tags?post=1523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}